{"id":6705,"date":"2017-03-14T20:33:00","date_gmt":"2017-03-14T19:33:00","guid":{"rendered":"http:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/?p=6705"},"modified":"2017-03-14T20:33:00","modified_gmt":"2017-03-14T19:33:00","slug":"wer-bier-braut-hat-treber-treberbrot-backen","status":"publish","type":"post","link":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wer-bier-braut-hat-treber-treberbrot-backen\/","title":{"rendered":"Wer Bier braut hat Treber &#8211; Treberbrot backen"},"content":{"rendered":"<p>Vom <a href=\"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/der-erste-brautag-sud-nr-1-weissbier\/\" target=\"_blank\" title=\"\">ersten Brautag<\/a> war einige Kilo Treber \u00fcbrig. <\/p>\n<div class=\"separator\" style=\"clear: both; text-align: none;\"><a href=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030404.jpg?ssl=1\" target=\"_blank\" style=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030404.jpg?resize=525%2C349&#038;ssl=1\" id=\"blogsy-1489519685029.2903\" class=\"alignnone\" alt=\"\" width=\"525\" height=\"349\"><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>Treber ist das ausgelaugte Malzschrot das nach dem Bierbrauen \u00fcbrig bleibt. Daraus kann man u.a. auch ein leckeres Treberbrot backen. <\/p>\n<p>Hier das Rezept:<\/p>\n<p>Zutaten:<\/p>\n<ul>\n<li>250g Weizenmehl Typ 550<\/li>\n<li>250g Roggenmehl Typ 997<\/li>\n<li>250g Treber<\/li>\n<li>250ml Bier (Ich habe etwas von meinem India Pale Ale geopfert)<\/li>\n<li>1 Pck Trockenbackhefe<\/li>\n<li>2 Teel\u00f6ffel Salz<\/li>\n<li>Eine Handvoll K\u00fcrbiskerne<\/li>\n<\/ul>\n<p>Zuerst werden die K\u00fcrbiskerne in einer Pfanne ger\u00f6stet.<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: none;\"><a href=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030483.jpg?ssl=1\" target=\"_blank\" style=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030483.jpg?resize=525%2C349&#038;ssl=1\" id=\"blogsy-1489519684945.5574\" class=\"alignnone\" alt=\"\" width=\"525\" height=\"349\"><\/a><\/div>\n<p>Dann werden alle Zutaten verknetet.<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: none;\"><a href=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030553.jpg?ssl=1\" target=\"_blank\" style=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030553.jpg?resize=525%2C349&#038;ssl=1\" id=\"blogsy-1489519685001.3174\" class=\"alignnone\" alt=\"\" width=\"525\" height=\"349\"><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>1 Stunde muss der Teig nun an einem warmen Ort gehen. <\/p>\n<p>Wieder durchkneten und nocheinmal 30 Minuten ruhen lassen.<\/p>\n<p>Dann ab in den Backofen mit Pizzastein (275\u00b0C vorgeheizt). Ich habe Kastenformen verwendet und zwei Rezepte dieser Brote zusammen gebacken. Nach 15 Minuten auf 200\u00b0C runterstellen mit kaltem Wasser bepinseln und noch weitere 60 Minuten backen.<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: none;\"><a href=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030655.jpg?ssl=1\" target=\"_blank\" style=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030655.jpg?resize=525%2C349&#038;ssl=1\" id=\"blogsy-1489519684960.466\" class=\"alignnone\" alt=\"\" width=\"525\" height=\"349\"><\/a><\/div>\n<p> Das Brot ist sehr lecker. Es wurde von der Familie gleich mit Butter probiert und f\u00fcr gut befunden :-). Die ger\u00f6steten K\u00fcrbiskerne passen gut dazu. Beim n\u00e4chsten Brautag mache ich das Rezept noch einmal.<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: none;\"><a href=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030736.jpg?ssl=1\" target=\"_blank\" style=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-content\/uploads\/2017\/03\/Photo-20170312232030736.jpg?resize=525%2C387&#038;ssl=1\" id=\"blogsy-1489519685006.616\" class=\"alignnone\" alt=\"\" width=\"525\" height=\"387\"><\/a><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vom ersten Brautag war einige Kilo Treber \u00fcbrig. &nbsp; Treber ist das ausgelaugte Malzschrot das nach dem Bierbrauen \u00fcbrig bleibt. Daraus kann man u.a. auch ein leckeres Treberbrot backen. Hier das Rezept: Zutaten: 250g Weizenmehl Typ 550 250g Roggenmehl Typ 997 250g Treber 250ml Bier (Ich habe etwas von meinem India Pale Ale geopfert) 1 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wer-bier-braut-hat-treber-treberbrot-backen\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eWer Bier braut hat Treber &#8211; Treberbrot backen\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[274,336],"tags":[233,367,338,225,213,366],"class_list":["post-6705","post","type-post","status-publish","format-standard","hentry","category-backen","category-brauen","tag-backen","tag-bier","tag-brauen","tag-brot","tag-hefeteig","tag-treber"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/pOqQt-1K9","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/posts\/6705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/comments?post=6705"}],"version-history":[{"count":2,"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/posts\/6705\/revisions"}],"predecessor-version":[{"id":6717,"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/posts\/6705\/revisions\/6717"}],"wp:attachment":[{"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/media?parent=6705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/categories?post=6705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irrlicht-geocaching.de\/irrlichtblog\/wp-json\/wp\/v2\/tags?post=6705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}